{"id":782843,"date":"2025-05-07T18:44:18","date_gmt":"2025-05-07T16:44:18","guid":{"rendered":"https:\/\/strohm-teka.com\/producto\/833461280\/"},"modified":"2026-05-29T14:06:30","modified_gmt":"2026-05-29T12:06:30","slug":"833461280","status":"publish","type":"product","link":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/","title":{"rendered":"Grifo de lavabo m"},"content":{"rendered":"<p>Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8&#8243; incluidas.<\/p>\n","protected":false},"excerpt":{"rendered":"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea&#8230;","protected":false},"featured_media":901305,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3409,3423],"product_tag":[],"class_list":{"0":"post-782843","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_collection-sineu","7":"product_finishes-cromo","8":"product_cat-griferia","9":"product_cat-grifo-de-lavabo-m","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grifo de lavabo m - Strohm Teka<\/title>\n<meta name=\"description\" content=\"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8&quot; incluidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grifo de lavabo m - Strohm Teka\" \/>\n<meta property=\"og:description\" content=\"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8&quot; incluidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/\" \/>\n<meta property=\"og:site_name\" content=\"Strohm Teka\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T12:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/14082707\/782843_1778740027_-833461250_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/\",\"name\":\"Grifo de lavabo m - Strohm Teka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29140631\\\/782843_1780056391_-833461250_01.jpg\",\"datePublished\":\"2025-05-07T16:44:18+00:00\",\"dateModified\":\"2026-05-29T12:06:30+00:00\",\"description\":\"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\\\/8\\\" incluidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29140631\\\/782843_1780056391_-833461250_01.jpg\",\"contentUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29140631\\\/782843_1780056391_-833461250_01.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/produkt\\\/833461280\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/strohm-teka.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grifo de lavabo m\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/\",\"name\":\"Strohm Teka\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#organization\",\"name\":\"Strohm Teka\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2021\\\/01\\\/strohm_teka_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2021\\\/01\\\/strohm_teka_logo.jpg\",\"width\":738,\"height\":354,\"caption\":\"Strohm Teka\"},\"image\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/strohm_teka_es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teka-strohm-espa\u00f1a\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grifo de lavabo m - Strohm Teka","description":"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8\" incluidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/","og_locale":"de_DE","og_type":"article","og_title":"Grifo de lavabo m - Strohm Teka","og_description":"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8\" incluidas.","og_url":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/","og_site_name":"Strohm Teka","article_modified_time":"2026-05-29T12:06:30+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/14082707\/782843_1778740027_-833461250_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/","url":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/","name":"Grifo de lavabo m - Strohm Teka","isPartOf":{"@id":"https:\/\/strohm-teka.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/#primaryimage"},"image":{"@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/#primaryimage"},"thumbnailUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29140631\/782843_1780056391_-833461250_01.jpg","datePublished":"2025-05-07T16:44:18+00:00","dateModified":"2026-05-29T12:06:30+00:00","description":"Grifo para lavabo monomando Sineu, es un grifo sencillo pero completo ya que tiene un limitador de caudal de 5 litros por minuto que permite ahorrar agua en cada uso. Este grifo es perfecto para reemplazos r\u00e1pido y es ideal para proyectos BREEAM Y LEED. Su aireador antical hace que la limpieza del grifo sea m\u00e1s f\u00e1cil y su dise\u00f1o es perfecto para cualquier ba\u00f1o. Este grifo tiene conexiones flexibles de 3\/8\" incluidas.","breadcrumb":{"@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strohm-teka.com\/de\/produkt\/833461280\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/#primaryimage","url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29140631\/782843_1780056391_-833461250_01.jpg","contentUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29140631\/782843_1780056391_-833461250_01.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/strohm-teka.com\/de\/produkt\/833461280\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/strohm-teka.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/strohm-teka.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Grifo de lavabo m"}]},{"@type":"WebSite","@id":"https:\/\/strohm-teka.com\/de\/#website","url":"https:\/\/strohm-teka.com\/de\/","name":"Strohm Teka","description":"","publisher":{"@id":"https:\/\/strohm-teka.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strohm-teka.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/strohm-teka.com\/de\/#organization","name":"Strohm Teka","url":"https:\/\/strohm-teka.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/strohm-teka.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2021\/01\/strohm_teka_logo.jpg","contentUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2021\/01\/strohm_teka_logo.jpg","width":738,"height":354,"caption":"Strohm Teka"},"image":{"@id":"https:\/\/strohm-teka.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/strohm_teka_es\/","https:\/\/www.linkedin.com\/company\/teka-strohm-espa\u00f1a\/"]}]}},"_links":{"self":[{"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/product\/782843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/media\/901305"}],"wp:attachment":[{"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/media?parent=782843"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/product_brand?post=782843"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/product_cat?post=782843"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/strohm-teka.com\/de\/wp-json\/wp\/v2\/product_tag?post=782843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}