{"id":783956,"date":"2025-05-07T18:50:42","date_gmt":"2025-05-07T16:50:42","guid":{"rendered":"https:\/\/strohm-teka.com\/producto\/187360003\/"},"modified":"2026-05-29T14:41:17","modified_gmt":"2026-05-29T12:41:17","slug":"187360003","status":"publish","type":"product","link":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/","title":{"rendered":"Bid\u00e9 a suelo"},"content":{"rendered":"<p>El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio.<\/p>\n<p>Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia&#8230;","protected":false},"featured_media":902589,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3473,3457],"product_tag":[],"class_list":{"0":"post-783956","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_collection-gloria","7":"product_finishes-blanco-brillo","8":"product_cat-bide-a-suelo","9":"product_cat-inodoros-y-bides","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bid\u00e9 a suelo - Strohm Teka<\/title>\n<meta name=\"description\" content=\"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bid\u00e9 a suelo - Strohm Teka\" \/>\n<meta property=\"og:description\" content=\"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/\" \/>\n<meta property=\"og:site_name\" content=\"Strohm Teka\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T12:41:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/27120421\/783956_1769511861_-187360003_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/\",\"name\":\"Bid\u00e9 a suelo - Strohm Teka\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29144117\\\/783956_1780058477_-187360003_01.png\",\"datePublished\":\"2025-05-07T16:50:42+00:00\",\"dateModified\":\"2026-05-29T12:41:17+00:00\",\"description\":\"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/#primaryimage\",\"url\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29144117\\\/783956_1780058477_-187360003_01.png\",\"contentUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2025\\\/05\\\/29144117\\\/783956_1780058477_-187360003_01.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/produkt\\\/187360003\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/strohm-teka.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bid\u00e9 a suelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/\",\"name\":\"Strohm Teka\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#organization\",\"name\":\"Strohm Teka\",\"url\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2021\\\/01\\\/strohm_teka_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/strohm-wp-services.1s.funcionalia.com\\\/2021\\\/01\\\/strohm_teka_logo.jpg\",\"width\":738,\"height\":354,\"caption\":\"Strohm Teka\"},\"image\":{\"@id\":\"https:\\\/\\\/strohm-teka.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/strohm_teka_es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teka-strohm-espa\u00f1a\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bid\u00e9 a suelo - Strohm Teka","description":"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/","og_locale":"pl_PL","og_type":"article","og_title":"Bid\u00e9 a suelo - Strohm Teka","og_description":"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.","og_url":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/","og_site_name":"Strohm Teka","article_modified_time":"2026-05-29T12:41:17+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/27120421\/783956_1769511861_-187360003_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/","url":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/","name":"Bid\u00e9 a suelo - Strohm Teka","isPartOf":{"@id":"https:\/\/strohm-teka.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/#primaryimage"},"image":{"@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/#primaryimage"},"thumbnailUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29144117\/783956_1780058477_-187360003_01.png","datePublished":"2025-05-07T16:50:42+00:00","dateModified":"2026-05-29T12:41:17+00:00","description":"El bid\u00e9 Gloria es la elecci\u00f3n ideal para quienes buscan un conjunto de ba\u00f1o elegante y funcional. Dise\u00f1ado para combinar perfectamente con el inodoro a suelo Gloria, este bid\u00e9 mantiene la misma l\u00ednea cl\u00e1sica y atemporal, aportando equilibrio est\u00e9tico y coherencia al espacio. Fabricado en cer\u00e1mica de alta calidad, el bid\u00e9 Gloria garantiza durabilidad, resistencia y f\u00e1cil limpieza, convirti\u00e9ndose en una soluci\u00f3n pr\u00e1ctica y duradera para el d\u00eda a d\u00eda.","breadcrumb":{"@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/#primaryimage","url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29144117\/783956_1780058477_-187360003_01.png","contentUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2025\/05\/29144117\/783956_1780058477_-187360003_01.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/strohm-teka.com\/pl\/produkt\/187360003\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/strohm-teka.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/strohm-teka.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Bid\u00e9 a suelo"}]},{"@type":"WebSite","@id":"https:\/\/strohm-teka.com\/pl\/#website","url":"https:\/\/strohm-teka.com\/pl\/","name":"Strohm Teka","description":"","publisher":{"@id":"https:\/\/strohm-teka.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/strohm-teka.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/strohm-teka.com\/pl\/#organization","name":"Strohm Teka","url":"https:\/\/strohm-teka.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/strohm-teka.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2021\/01\/strohm_teka_logo.jpg","contentUrl":"https:\/\/strohm-wp-services.1s.funcionalia.com\/2021\/01\/strohm_teka_logo.jpg","width":738,"height":354,"caption":"Strohm Teka"},"image":{"@id":"https:\/\/strohm-teka.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/strohm_teka_es\/","https:\/\/www.linkedin.com\/company\/teka-strohm-espa\u00f1a\/"]}]}},"_links":{"self":[{"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/product\/783956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/media\/902589"}],"wp:attachment":[{"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/media?parent=783956"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/product_brand?post=783956"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/product_cat?post=783956"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/strohm-teka.com\/pl\/wp-json\/wp\/v2\/product_tag?post=783956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}